{"id":19764,"date":"2023-08-06T23:17:24","date_gmt":"2023-08-06T21:17:24","guid":{"rendered":"https:\/\/www.classicclubitalia.it\/classic\/?p=19764"},"modified":"2023-08-06T23:17:28","modified_gmt":"2023-08-06T21:17:28","slug":"targhe-originali-decreto-approvato","status":"publish","type":"post","link":"https:\/\/www.classicclubitalia.it\/classic\/targhe-originali-decreto-approvato\/","title":{"rendered":"Targhe originali &#8211; Decreto approvato"},"content":{"rendered":"\n<p>IL MINISTERO DELLE INFRASTRUTTURE E DEI TRASPORTI HA EMANATO IL DECRETO ATTUATIVO PER LE TARGHE ORIGINALI DEI VEICOLI STORICI<\/p>\n\n\n\n<p>SI CHIUDE CON SUCCESSO L\u2019ITER NORMATIVO AVVIATO NEL 2020 GRAZIE ALLA SENSIBILIZZAZIONE DI ASI E DI ALTRI STAKEHOLDER DEL SETTORE NEI CONFRONTI DI UN CORREDO STORICO IMPORTANTE CHE COMPLETA L\u2019ORIGINALIT\u00c0 DEI MEZZI<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/www.classicclubitalia.it\/classic\/wp-content\/uploads\/2023\/08\/060823-decreto-targhe-cs-asi.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">SCARICA IL COMUNICATO STAMPA ASI IN FORMATO PDF<\/a><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.classicclubitalia.it\/classic\/wp-content\/uploads\/2023\/08\/ASI-Targhe-originali-veicoli-storici-1024x683.jpg\" alt=\"\" class=\"wp-image-19766\" srcset=\"https:\/\/www.classicclubitalia.it\/classic\/wp-content\/uploads\/2023\/08\/ASI-Targhe-originali-veicoli-storici-1024x683.jpg 1024w, https:\/\/www.classicclubitalia.it\/classic\/wp-content\/uploads\/2023\/08\/ASI-Targhe-originali-veicoli-storici-300x200.jpg 300w, https:\/\/www.classicclubitalia.it\/classic\/wp-content\/uploads\/2023\/08\/ASI-Targhe-originali-veicoli-storici-768x512.jpg 768w, https:\/\/www.classicclubitalia.it\/classic\/wp-content\/uploads\/2023\/08\/ASI-Targhe-originali-veicoli-storici-1536x1025.jpg 1536w, https:\/\/www.classicclubitalia.it\/classic\/wp-content\/uploads\/2023\/08\/ASI-Targhe-originali-veicoli-storici-570x380.jpg 570w, https:\/\/www.classicclubitalia.it\/classic\/wp-content\/uploads\/2023\/08\/ASI-Targhe-originali-veicoli-storici.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">Il Ministero delle Infrastrutture e dei Trasporti ha emanato il decreto attuativo per la legge 178 del 30 dicembre 2020 che prevede la \u201cfacolt\u00e0 di ottenere le targhe di circolazione della prima iscrizione al Pubblico Registro  Automobilistico, ovvero di ottenere una targa del periodo storico di costruzione o di circolazione per i veicoli di interesse storico e collezionistico\u201d.<br><br>Il Ministro Matteo Salvini ha firmato il decreto venerd\u00ec 4 agosto e lo stesso entrer\u00e0 in vigore il giorno della<br>pubblicazione in Gazzetta Ufficiale (presumibile luned\u00ec 7 agosto) e sar\u00e0 applicabile dal sessantesimo giorno<br>successivo alla predetta data.<br><br>Da quel momento sar\u00e0 quindi possibile dotare il proprio veicolo di interesse storico e collezionistico (individuato mediante il Certificato di Rilevanza Storica come da art. 60 del Codice della Strada) di quel prezioso corredo che ne completa le caratteristiche di originalit\u00e0: un obiettivo che ASI, insieme agli altri attori, perseguivano da tempo sensibilizzando il legislatore sulla formulazione di normative nazionali che tutelino sempre di pi\u00f9 e sempre meglio il settore del motorismo storico.<br><br>Il decreto attuativo appena emanato determina e indica chiaramente le modalit\u00e0 di applicazione della legge, a partire dalla richiesta che il proprietario dovr\u00e0 presentare presso uno STA (Sportello Telematico dell\u2019Automobilista) o un Ufficio della Motorizzazione Civile. Le istanze posso essere avanzate per i veicoli radiati d\u2019ufficio o per esportazione, per quelli reimmatricolati e per quelli di origine sconosciuta, in ogni caso dotati di Certificato di Rilevanza Storica.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Il rilascio della targa storica \u00e8 soggetto al pagamento di 549,00 euro per gli autoveicoli e 274,50 euro per i motocicli e le macchine agricole.<br><br>\u201cSiamo felici \u2013 dichiara il Ministro Salvini \u2013 di aver potuto concludere l\u2019iter attuativo di una norma tanto voluta e tanto attesa dagli appassionati, mettendo a sistema i diversi dipartimenti coinvolti\u201d. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u201cUn decreto \u2013 sottolinea Alberto Scuro, Presidente ASI &#8211; che arriva dopo aver svolto una importante mole di lavoro per sottolineare al Ministero, alla Motorizzazione e al Poligrafico dello Stato l\u2019importanza che ha per gli appassionati la possibilit\u00e0 di ristabilire l\u2019originalit\u00e0 pi\u00f9 completa dei propri veicoli storici. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">Inseguire l\u2019originalit\u00e0 fa parte della nostra mission e la targa di nascita \u00e8 parte integrante del veicolo stesso: per<br>questo ringraziamo la sensibilit\u00e0 dimostrata dalla politica in generale e dal Ministro Salvini in particolare che, dopo essere stato sensibilizzato sull\u2019importanza dell\u2019iniziativa che non comportava alcun onere per lo Stato \u00e8 riuscito a dare il via alla sua applicazione in tempi brevissimi\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>IL MINISTERO DELLE INFRASTRUTTURE E DEI TRASPORTI HA EMANATO IL DECRETO ATTUATIVO PER LE TARGHE ORIGINALI DEI VEICOLI STORICI SI CHIUDE CON SUCCESSO L\u2019ITER NORMATIVO AVVIATO NEL 2020 GRAZIE ALLA SENSIBILIZZAZIONE DI ASI E DI ALTRI STAKEHOLDER DEL SETTORE NEI CONFRONTI DI UN CORREDO STORICO IMPORTANTE CHE COMPLETA L\u2019ORIGINALIT\u00c0 DEI MEZZI SCARICA IL COMUNICATO STAMPA [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[14],"tags":[],"class_list":{"0":"post-19764","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-avvisi-home","8":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/www.classicclubitalia.it\/classic\/wp-json\/wp\/v2\/posts\/19764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.classicclubitalia.it\/classic\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.classicclubitalia.it\/classic\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.classicclubitalia.it\/classic\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.classicclubitalia.it\/classic\/wp-json\/wp\/v2\/comments?post=19764"}],"version-history":[{"count":0,"href":"https:\/\/www.classicclubitalia.it\/classic\/wp-json\/wp\/v2\/posts\/19764\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.classicclubitalia.it\/classic\/wp-json\/wp\/v2\/media\/16540"}],"wp:attachment":[{"href":"https:\/\/www.classicclubitalia.it\/classic\/wp-json\/wp\/v2\/media?parent=19764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.classicclubitalia.it\/classic\/wp-json\/wp\/v2\/categories?post=19764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.classicclubitalia.it\/classic\/wp-json\/wp\/v2\/tags?post=19764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}